{"id":11900,"date":"2024-04-16T08:51:15","date_gmt":"2024-04-16T13:51:15","guid":{"rendered":"https:\/\/optimas.com\/?page_id=11900"},"modified":"2026-07-08T15:58:24","modified_gmt":"2026-07-08T20:58:24","slug":"iso-metric-thread-proof-loads","status":"publish","type":"page","link":"https:\/\/optimas.com\/es\/technical-resources\/iso-metric-thread-proof-loads\/","title":{"rendered":"Cargas de prueba de rosca m\u00e9trica ISO"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling max\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:0px;--awb-padding-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column max1200\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><nav class=\"fusion-breadcrumbs fusion-breadcrumbs-1\" style=\"--awb-alignment:left;--awb-font-size:16;--awb-text-color:#e87722;--awb-breadcrumb-sep:&#039;\/&#039;;text-align:left;\" aria-label=\"Migaja de pan\"><ol class=\"awb-breadcrumb-list\"><li class=\"fusion-breadcrumb-item awb-breadcrumb-sep awb-home\" ><a href=\"https:\/\/optimas.com\/es\/\" class=\"fusion-breadcrumb-link\"><span >Hogar<\/span><\/a><\/li><\/ol><\/nav><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:0px;--awb-padding-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column max1200\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_2_5 2_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:40%;--awb-margin-top-large:0px;--awb-spacing-right-large:4.8%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:4.8%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"573\" height=\"436\" alt=\"A high-quality fastener for businesses to maintain operation efficiency\" title=\"est\u00e1ndar\" src=\"https:\/\/optimas.com\/wp-content\/uploads\/2024\/04\/standard.jpg\" class=\"img-responsive wp-image-11706\" srcset=\"https:\/\/optimas.com\/wp-content\/uploads\/2024\/04\/standard-200x152.jpg 200w, https:\/\/optimas.com\/wp-content\/uploads\/2024\/04\/standard-400x304.jpg 400w, https:\/\/optimas.com\/wp-content\/uploads\/2024\/04\/standard.jpg 573w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 573px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_3_5 3_5 fusion-flex-column fusion-flex-align-self-center\" style=\"--awb-bg-size:cover;--awb-width-large:60%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.2%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.2%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><div class=\"fusion-text fusion-text-1\">\n<p>&nbsp;<\/p>\n<h2>Cargas de prueba de rosca de paso m\u00e9trico ISO<\/h2>\n<\/div>\n<div class=\"fusion-text fusion-text-2\">\n<p>Optimas are a full-service supply chain and <a href=\"https:\/\/optimas.com\/es\/services\/manufacturing\/\">fabricaci\u00f3n<\/a> solutions provider. Before you design your next product or make updates to an existing product, consider partnering with Optimas to take advantage of our many capabilities.<\/p>\n<\/div>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:20px;margin-bottom:20px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-2\"><p><a class=\"linkOrangeButton\" href=\"https:\/\/optimas.com\/es\/contact\/\">HABLE CON UN EXPERTO<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:1px;\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column max1200\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:10px;margin-bottom:10px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-3\"><p>La siguiente tabla muestra las cargas de prueba para pernos, tuercas y esp\u00e1rragos con rosca m\u00e9trica ISO de paso grueso y fino en tama\u00f1os M3 a M39.<\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:10px;margin-bottom:10px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-4\"><p style=\"font-size: 18px;\" data-fusion-font=\"true\">Seg\u00fan EN ISO 898-1.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling overflow-x :scroll;\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column max1200\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-tabs fusion-tabs-1 classic nav-not-justified overflow-x: scroll; horizontal-tabs icon-position-left mobile-mode-accordion\" style=\"--awb-title-border-radius-top-left:0px;--awb-title-border-radius-top-right:0px;--awb-title-border-radius-bottom-right:0px;--awb-title-border-radius-bottom-left:0px;--awb-alignment:start;--awb-inactive-color:#ebeaea;--awb-background-color:#ffffff;--awb-border-color:#ebeaea;--awb-active-border-color:#ee7724;\"><div class=\"nav\"><ul class=\"nav-tabs\" role=\"tablist\" aria-orientation=\"horizontal\"><li class=\"active\" role=\"presentation\"><a class=\"tab-link\" data-toggle=\"tab\" role=\"tab\" aria-controls=\"tab-4f1457601a87410156f\" aria-selected=\"true\" tabindex=\"0\" id=\"fusion-tab-4f1457601a87410156f\" href=\"#tab-4f1457601a87410156f\"><h4 class=\"fusion-tab-heading\">Rosca de paso grueso<\/h4><\/a><\/li><li  role=\"presentation\"><a class=\"tab-link\" data-toggle=\"tab\" role=\"tab\" aria-controls=\"tab-f141d725e5cfa1bf500\" aria-selected=\"false\" tabindex=\"-1\" id=\"fusion-tab-f141d725e5cfa1bf500\" href=\"#tab-f141d725e5cfa1bf500\"><h4 class=\"fusion-tab-heading\">Hilo de paso fino<\/h4><\/a><\/li><\/ul><\/div><div class=\"tab-content\"><div class=\"nav fusion-mobile-tab-nav\"><ul class=\"nav-tabs\" role=\"tablist\" aria-orientation=\"horizontal\"><li class=\"active\" role=\"presentation\"><a class=\"tab-link\" data-toggle=\"tab\" role=\"tab\" aria-controls=\"tab-4f1457601a87410156f\" aria-selected=\"true\" tabindex=\"0\" id=\"mobile-fusion-tab-4f1457601a87410156f\" href=\"#tab-4f1457601a87410156f\"><h4 class=\"fusion-tab-heading\">Rosca de paso grueso<\/h4><\/a><\/li><\/ul><\/div><div class=\"tab-pane fade fusion-clearfix in active\" role=\"tabpanel\" tabindex=\"0\" aria-labelledby=\"fusion-tab-4f1457601a87410156f\" id=\"tab-4f1457601a87410156f\">\n<table id=\"tablepress-12\" class=\"tablepress tablepress-id-12 tbody-has-connected-cells\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Hilo<sup>a<\/sup>\u00a0d<\/th><th class=\"column-2\">\u00c1rea de tensi\u00f3n nominal A<sup>s,nombre<\/sup>bmm<sup>2<\/sup><\/th><th colspan=\"9\" class=\"column-3\">Clase de propiedad<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td rowspan=\"2\" class=\"column-1\"><\/td><td rowspan=\"2\" class=\"column-2\"><\/td><td class=\"column-3\"><strong>4.6<\/strong><\/td><td class=\"column-4\"><strong>4.8<\/strong><\/td><td class=\"column-5\"><strong>5.6<\/strong><\/td><td class=\"column-6\"><strong>5.8<\/strong><\/td><td class=\"column-7\"><strong>6.8<\/strong><\/td><td class=\"column-8\"><strong>8.8<\/strong><\/td><td class=\"column-9\"><strong>9.8<\/strong><\/td><td class=\"column-10\"><strong>10.9<\/strong><\/td><td class=\"column-11\"><strong>12.9\/12.9<\/strong><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td colspan=\"9\" class=\"column-3\"><strong>Carga de prueba, F<sup>pag<\/sup>\u00a0(A<sup>s,nombre<\/sup>\u00a0x S<sup>p,nom.<\/sup>), norte<\/strong><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">M3<\/td><td class=\"column-2\">5,03<\/td><td class=\"column-3\">1130<\/td><td class=\"column-4\">1560<\/td><td class=\"column-5\">1410<\/td><td class=\"column-6\">1910<\/td><td class=\"column-7\">2210<\/td><td class=\"column-8\">2920<\/td><td class=\"column-9\">3270<\/td><td class=\"column-10\">4180<\/td><td class=\"column-11\">4880<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">M3,5<\/td><td class=\"column-2\">6,78<\/td><td class=\"column-3\">1530<\/td><td class=\"column-4\">2100<\/td><td class=\"column-5\">1900<\/td><td class=\"column-6\">2580<\/td><td class=\"column-7\">2980<\/td><td class=\"column-8\">3940<\/td><td class=\"column-9\">4410<\/td><td class=\"column-10\">5630<\/td><td class=\"column-11\">6580<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">M4<\/td><td class=\"column-2\">8,78<\/td><td class=\"column-3\">1980<\/td><td class=\"column-4\">2720<\/td><td class=\"column-5\">2460<\/td><td class=\"column-6\">3340<\/td><td class=\"column-7\">3860<\/td><td class=\"column-8\">5100<\/td><td class=\"column-9\">5710<\/td><td class=\"column-10\">7290<\/td><td class=\"column-11\">8520<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">M5<\/td><td class=\"column-2\">14,2<\/td><td class=\"column-3\">3200<\/td><td class=\"column-4\">4400<\/td><td class=\"column-5\">3980<\/td><td class=\"column-6\">5400<\/td><td class=\"column-7\">6250<\/td><td class=\"column-8\">8230<\/td><td class=\"column-9\">9230<\/td><td class=\"column-10\">11800<\/td><td class=\"column-11\">13800<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">M6<\/td><td class=\"column-2\">20,1<\/td><td class=\"column-3\">4520<\/td><td class=\"column-4\">6230<\/td><td class=\"column-5\">5630<\/td><td class=\"column-6\">7640<\/td><td class=\"column-7\">8840<\/td><td class=\"column-8\">11600<\/td><td class=\"column-9\">13100<\/td><td class=\"column-10\">16700<\/td><td class=\"column-11\">19500<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">M7<\/td><td class=\"column-2\">28,9<\/td><td class=\"column-3\">6500<\/td><td class=\"column-4\">8960<\/td><td class=\"column-5\">8090<\/td><td class=\"column-6\">11000<\/td><td class=\"column-7\">12700<\/td><td class=\"column-8\">16800<\/td><td class=\"column-9\">18800<\/td><td class=\"column-10\">24000<\/td><td class=\"column-11\">28000<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">M8<\/td><td class=\"column-2\">36,6<\/td><td class=\"column-3\">8240\u00a0<sup>C<\/sup><\/td><td class=\"column-4\">11400<\/td><td class=\"column-5\">10200\u00a0<sup>C<\/sup><\/td><td class=\"column-6\">13900<\/td><td class=\"column-7\">16100<\/td><td class=\"column-8\">21200\u00a0<sup>C<\/sup><\/td><td class=\"column-9\">23800<\/td><td class=\"column-10\">30400c<\/td><td class=\"column-11\">35500<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">M10<\/td><td class=\"column-2\">58<\/td><td class=\"column-3\">13000\u00a0<sup>C<\/sup><\/td><td class=\"column-4\">18000<\/td><td class=\"column-5\">16200\u00a0<sup>C<\/sup><\/td><td class=\"column-6\">22000<\/td><td class=\"column-7\">25500<\/td><td class=\"column-8\">33700\u00a0<sup>C<\/sup><\/td><td class=\"column-9\">37700<\/td><td class=\"column-10\">48100c<\/td><td class=\"column-11\">56300<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">M12<\/td><td class=\"column-2\">84,3<\/td><td class=\"column-3\">19000<\/td><td class=\"column-4\">26100<\/td><td class=\"column-5\">23600<\/td><td class=\"column-6\">32000<\/td><td class=\"column-7\">37100<\/td><td class=\"column-8\">48900\u00a0<sup>d<\/sup><\/td><td class=\"column-9\">54800<\/td><td class=\"column-10\">70000<\/td><td class=\"column-11\">81800<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">M14<\/td><td class=\"column-2\">115<\/td><td class=\"column-3\">25900<\/td><td class=\"column-4\">35600<\/td><td class=\"column-5\">32200<\/td><td class=\"column-6\">43700<\/td><td class=\"column-7\">50600<\/td><td class=\"column-8\">66700\u00a0<sup>d<\/sup><\/td><td class=\"column-9\">74800<\/td><td class=\"column-10\">95500<\/td><td class=\"column-11\">112000<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">M16<\/td><td class=\"column-2\">157<\/td><td class=\"column-3\">35300<\/td><td class=\"column-4\">48700<\/td><td class=\"column-5\">44000<\/td><td class=\"column-6\">59700<\/td><td class=\"column-7\">69100<\/td><td class=\"column-8\">91000\u00a0<sup>d<\/sup><\/td><td class=\"column-9\">102000<\/td><td class=\"column-10\">130000<\/td><td class=\"column-11\">152000<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">M18<\/td><td class=\"column-2\">192<\/td><td class=\"column-3\">43200<\/td><td class=\"column-4\">59500<\/td><td class=\"column-5\">53800<\/td><td class=\"column-6\">73000<\/td><td class=\"column-7\">84500<\/td><td class=\"column-8\">115000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">159000<\/td><td class=\"column-11\">186000<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">M20<\/td><td class=\"column-2\">245<\/td><td class=\"column-3\">55100<\/td><td class=\"column-4\">76000<\/td><td class=\"column-5\">68600<\/td><td class=\"column-6\">93100<\/td><td class=\"column-7\">108000<\/td><td class=\"column-8\">147000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">203000<\/td><td class=\"column-11\">238000<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">M22<\/td><td class=\"column-2\">303<\/td><td class=\"column-3\">68200<\/td><td class=\"column-4\">93900<\/td><td class=\"column-5\">84800<\/td><td class=\"column-6\">115000<\/td><td class=\"column-7\">133000<\/td><td class=\"column-8\">182000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">252000<\/td><td class=\"column-11\">294000<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">M24<\/td><td class=\"column-2\">353<\/td><td class=\"column-3\">79400<\/td><td class=\"column-4\">109000<\/td><td class=\"column-5\">98800<\/td><td class=\"column-6\">134000<\/td><td class=\"column-7\">155000<\/td><td class=\"column-8\">212000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">293000<\/td><td class=\"column-11\">342000<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">M27<\/td><td class=\"column-2\">459<\/td><td class=\"column-3\">103000<\/td><td class=\"column-4\">142000<\/td><td class=\"column-5\">128000<\/td><td class=\"column-6\">174000<\/td><td class=\"column-7\">202000<\/td><td class=\"column-8\">275000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">381000<\/td><td class=\"column-11\">445000<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">M30<\/td><td class=\"column-2\">561<\/td><td class=\"column-3\">126000<\/td><td class=\"column-4\">174000<\/td><td class=\"column-5\">157000<\/td><td class=\"column-6\">213000<\/td><td class=\"column-7\">247000<\/td><td class=\"column-8\">337000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">466000<\/td><td class=\"column-11\">544000<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">M33<\/td><td class=\"column-2\">694<\/td><td class=\"column-3\">156000<\/td><td class=\"column-4\">215000<\/td><td class=\"column-5\">194000<\/td><td class=\"column-6\">264000<\/td><td class=\"column-7\">305000<\/td><td class=\"column-8\">416000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">576000<\/td><td class=\"column-11\">673000<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">M36<\/td><td class=\"column-2\">817<\/td><td class=\"column-3\">184000<\/td><td class=\"column-4\">253000<\/td><td class=\"column-5\">229000<\/td><td class=\"column-6\">310000<\/td><td class=\"column-7\">359000<\/td><td class=\"column-8\">490000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">678000<\/td><td class=\"column-11\">792000<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">M39<\/td><td class=\"column-2\">976<\/td><td class=\"column-3\">220000<\/td><td class=\"column-4\">303000<\/td><td class=\"column-5\">273000<\/td><td class=\"column-6\">371000<\/td><td class=\"column-7\">429000<\/td><td class=\"column-8\">586000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">810000<\/td><td class=\"column-11\">947000<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><div class=\"nav fusion-mobile-tab-nav\"><ul class=\"nav-tabs\" role=\"tablist\" aria-orientation=\"horizontal\"><li  role=\"presentation\"><a class=\"tab-link\" data-toggle=\"tab\" role=\"tab\" aria-controls=\"tab-f141d725e5cfa1bf500\" aria-selected=\"false\" tabindex=\"-1\" id=\"mobile-fusion-tab-f141d725e5cfa1bf500\" href=\"#tab-f141d725e5cfa1bf500\"><h4 class=\"fusion-tab-heading\">Hilo de paso fino<\/h4><\/a><\/li><\/ul><\/div><div class=\"tab-pane fade fusion-clearfix\" role=\"tabpanel\" tabindex=\"0\" aria-labelledby=\"fusion-tab-f141d725e5cfa1bf500\" id=\"tab-f141d725e5cfa1bf500\">\n<table id=\"tablepress-14\" class=\"tablepress tablepress-id-14 tbody-has-connected-cells\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Hilo dx P<\/th><th class=\"column-2\">\u00c1rea de tensi\u00f3n nominal A<sup>s,nombre<\/sup>un mil\u00edmetro<sup>2<\/sup><\/th><th colspan=\"9\" class=\"column-3\">Clase de propiedad<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td rowspan=\"2\" class=\"column-1\"><\/td><td rowspan=\"2\" class=\"column-2\"><\/td><td class=\"column-3\"><strong>4.6<\/strong><\/td><td class=\"column-4\"><strong>4.8<\/strong><\/td><td class=\"column-5\"><strong>5.6<\/strong><\/td><td class=\"column-6\"><strong>5.8<\/strong><\/td><td class=\"column-7\"><strong>6.8<\/strong><\/td><td class=\"column-8\"><strong>8.8<\/strong><\/td><td class=\"column-9\"><strong>9.8<\/strong><\/td><td class=\"column-10\"><strong>10.9<\/strong><\/td><td class=\"column-11\"><strong>12.9\/12.9<\/strong><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td colspan=\"9\" class=\"column-3\">Carga de prueba, F<sup>pag<\/sup>\u00a0(A<sup>s,nombre<\/sup> x S<sup>p,nom.<\/sup>), norte<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">M8x1<\/td><td class=\"column-2\">39,2<\/td><td class=\"column-3\">8820<\/td><td class=\"column-4\">12200<\/td><td class=\"column-5\">11000<\/td><td class=\"column-6\">14900<\/td><td class=\"column-7\">17200<\/td><td class=\"column-8\">22700<\/td><td class=\"column-9\">25500<\/td><td class=\"column-10\">32500<\/td><td class=\"column-11\">38000<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">M10x1,25<\/td><td class=\"column-2\">61,2<\/td><td class=\"column-3\">13800<\/td><td class=\"column-4\">19000<\/td><td class=\"column-5\">17100<\/td><td class=\"column-6\">23300<\/td><td class=\"column-7\">26900<\/td><td class=\"column-8\">35500<\/td><td class=\"column-9\">39800<\/td><td class=\"column-10\">50800<\/td><td class=\"column-11\">59400<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">M10x1<\/td><td class=\"column-2\">64,5<\/td><td class=\"column-3\">14500<\/td><td class=\"column-4\">20000<\/td><td class=\"column-5\">18100<\/td><td class=\"column-6\">24500<\/td><td class=\"column-7\">28400<\/td><td class=\"column-8\">37400<\/td><td class=\"column-9\">41900<\/td><td class=\"column-10\">53500<\/td><td class=\"column-11\">62700<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">M12x1,5<\/td><td class=\"column-2\">88,1<\/td><td class=\"column-3\">19800<\/td><td class=\"column-4\">27300<\/td><td class=\"column-5\">24700<\/td><td class=\"column-6\">33500<\/td><td class=\"column-7\">38800<\/td><td class=\"column-8\">51100<\/td><td class=\"column-9\">57300<\/td><td class=\"column-10\">73100<\/td><td class=\"column-11\">85500<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">M12x1,25<\/td><td class=\"column-2\">92,1<\/td><td class=\"column-3\">20700<\/td><td class=\"column-4\">28600<\/td><td class=\"column-5\">25800<\/td><td class=\"column-6\">35000<\/td><td class=\"column-7\">40500<\/td><td class=\"column-8\">53400<\/td><td class=\"column-9\">59900<\/td><td class=\"column-10\">76400<\/td><td class=\"column-11\">89300<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">M14x1,5<\/td><td class=\"column-2\">125<\/td><td class=\"column-3\">28100<\/td><td class=\"column-4\">38800<\/td><td class=\"column-5\">35000<\/td><td class=\"column-6\">47500<\/td><td class=\"column-7\">55000<\/td><td class=\"column-8\">72500<\/td><td class=\"column-9\">81200<\/td><td class=\"column-10\">104000<\/td><td class=\"column-11\">121000<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">M16x1,5<\/td><td class=\"column-2\">167<\/td><td class=\"column-3\">37600<\/td><td class=\"column-4\">51800<\/td><td class=\"column-5\">46800<\/td><td class=\"column-6\">63500<\/td><td class=\"column-7\">73500<\/td><td class=\"column-8\">96900<\/td><td class=\"column-9\">109000<\/td><td class=\"column-10\">139000<\/td><td class=\"column-11\">162000<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">M18x1,5<\/td><td class=\"column-2\">216<\/td><td class=\"column-3\">48600<\/td><td class=\"column-4\">67000<\/td><td class=\"column-5\">60500<\/td><td class=\"column-6\">82100<\/td><td class=\"column-7\">95000<\/td><td class=\"column-8\">130000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">179000<\/td><td class=\"column-11\">210000<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">M20x1,5<\/td><td class=\"column-2\">272<\/td><td class=\"column-3\">61200<\/td><td class=\"column-4\">84300<\/td><td class=\"column-5\">76200<\/td><td class=\"column-6\">103000<\/td><td class=\"column-7\">120000<\/td><td class=\"column-8\">163000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">226000<\/td><td class=\"column-11\">264000<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">M22x1,5<\/td><td class=\"column-2\">333<\/td><td class=\"column-3\">74900<\/td><td class=\"column-4\">103000<\/td><td class=\"column-5\">93200<\/td><td class=\"column-6\">126000<\/td><td class=\"column-7\">146000<\/td><td class=\"column-8\">200000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">276000<\/td><td class=\"column-11\">323000<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">M24x2<\/td><td class=\"column-2\">384<\/td><td class=\"column-3\">86400<\/td><td class=\"column-4\">119000<\/td><td class=\"column-5\">108000<\/td><td class=\"column-6\">146000<\/td><td class=\"column-7\">169000<\/td><td class=\"column-8\">230000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">319000<\/td><td class=\"column-11\">372000<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">M27x2<\/td><td class=\"column-2\">496<\/td><td class=\"column-3\">112000<\/td><td class=\"column-4\">154000<\/td><td class=\"column-5\">139000<\/td><td class=\"column-6\">188000<\/td><td class=\"column-7\">218000<\/td><td class=\"column-8\">298000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">412000<\/td><td class=\"column-11\">481000<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">M30x2<\/td><td class=\"column-2\">621<\/td><td class=\"column-3\">140000<\/td><td class=\"column-4\">192000<\/td><td class=\"column-5\">174000<\/td><td class=\"column-6\">236000<\/td><td class=\"column-7\">273000<\/td><td class=\"column-8\">373000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">515000<\/td><td class=\"column-11\">602000<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">M33x2<\/td><td class=\"column-2\">761<\/td><td class=\"column-3\">171000<\/td><td class=\"column-4\">236000<\/td><td class=\"column-5\">213000<\/td><td class=\"column-6\">289000<\/td><td class=\"column-7\">335000<\/td><td class=\"column-8\">457000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">632000<\/td><td class=\"column-11\">738000<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">M36x3<\/td><td class=\"column-2\">865<\/td><td class=\"column-3\">195000<\/td><td class=\"column-4\">268000<\/td><td class=\"column-5\">242000<\/td><td class=\"column-6\">329000<\/td><td class=\"column-7\">381000<\/td><td class=\"column-8\">519000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">718000<\/td><td class=\"column-11\">839000<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">M39x3<\/td><td class=\"column-2\">1030<\/td><td class=\"column-3\">232000<\/td><td class=\"column-4\">319000<\/td><td class=\"column-5\">288000<\/td><td class=\"column-6\">391000<\/td><td class=\"column-7\">453000<\/td><td class=\"column-8\">618000<\/td><td class=\"column-9\">-<\/td><td class=\"column-10\">855000<\/td><td class=\"column-11\">999000<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-flex-column max1200\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-5\"><div class=\"fusion-text fusion-text-6\">\n<div class=\"fusion-text fusion-text-6\">\n<p><sup>a<\/sup>\u00a0Cuando no se indica ning\u00fan paso de rosca en la designaci\u00f3n de una rosca, se especifica un paso grueso.<\/p>\n<\/div>\n<div class=\"fusion-separator fusion-full-width-sep\"><\/div>\n<div class=\"fusion-text fusion-text-7\">\n<p><sup>b<\/sup>\u00a0Para calcular A<sup>s,nombre<\/sup>, consulte 9.1.6.1.<\/p>\n<\/div>\n<div class=\"fusion-separator fusion-full-width-sep\"><\/div>\n<div class=\"fusion-text fusion-text-8\">\n<p><sup>C<\/sup>\u00a0Para elementos de fijaci\u00f3n con tolerancia de rosca 6az seg\u00fan ISO 965-4 sujetos a galvanizado en caliente, se aplican valores reducidos seg\u00fan ISO 10684:2004, Anexo A.<\/p>\n<\/div>\n<div class=\"fusion-separator fusion-full-width-sep\"><\/div>\n<div class=\"fusion-text fusion-text-9\">\n<p><sup>d<\/sup>\u00a0Para pernos estructurales 50 700 N (para M12), 68 800 N (para M14) y 94 500 N (para M16).<\/p>\n<\/div>\n<\/div>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:10px;margin-bottom:10px;width:100%;\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:var(--awb-custom10);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:104%;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_1 1_1 fusion-flex-column max1200\" style=\"--awb-padding-top:35px;--awb-padding-bottom:35px;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-2 fusion_builder_column_inner_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:66.6666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:2.88%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-6\"><p style=\"font-size: 30px; color: #fff;\">Perm\u00edtanos ayudarle a encontrar eficiencias<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-3 fusion_builder_column_inner_1_3 1_3 fusion-flex-column fusion-flex-align-self-center\" style=\"--awb-bg-size:cover;--awb-width-large:33.3333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-text fusion-text-7\"><p><a class=\"linkSpeakExpert\" href=\"https:\/\/optimas.com\/es\/contact\/\">CONT\u00c1CTENOS<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":38,"featured_media":11901,"parent":11686,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-11900","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/optimas.com\/es\/wp-json\/wp\/v2\/pages\/11900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optimas.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/optimas.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/optimas.com\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/optimas.com\/es\/wp-json\/wp\/v2\/comments?post=11900"}],"version-history":[{"count":1,"href":"https:\/\/optimas.com\/es\/wp-json\/wp\/v2\/pages\/11900\/revisions"}],"predecessor-version":[{"id":16430,"href":"https:\/\/optimas.com\/es\/wp-json\/wp\/v2\/pages\/11900\/revisions\/16430"}],"up":[{"embeddable":true,"href":"https:\/\/optimas.com\/es\/wp-json\/wp\/v2\/pages\/11686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/optimas.com\/es\/wp-json\/wp\/v2\/media\/11901"}],"wp:attachment":[{"href":"https:\/\/optimas.com\/es\/wp-json\/wp\/v2\/media?parent=11900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}